{"id":32293,"date":"2021-08-09T13:57:29","date_gmt":"2021-08-09T11:57:29","guid":{"rendered":"https:\/\/bio-balkon.de\/?post_type=experten&#038;p=32293"},"modified":"2021-08-09T13:59:06","modified_gmt":"2021-08-09T11:59:06","slug":"angelika-fuerstler-3","status":"publish","type":"experten","link":"https:\/\/bio-balkon.de\/en\/experten\/angelika-fuerstler-3\/","title":{"rendered":"Ange\u00adli\u00adka F\u00fcrst\u00adler"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"32293\" class=\"elementor elementor-32293\" data-elementor-post-type=\"experten\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-176157c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"176157c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-480d6bc\" data-id=\"480d6bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd44a92 elementor-widget elementor-widget-template\" data-id=\"cd44a92\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"section\" data-elementor-id=\"32289\" class=\"elementor elementor-32289\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-647519e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"647519e7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-463c49f3\" data-id=\"463c49f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2255d221 elementor-widget elementor-widget-image\" data-id=\"2255d221\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/sprossen-micorgreens-angelika-fuerstler-150x150.avif\" class=\"attachment-thumbnail size-thumbnail wp-image-32285\" alt>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-759eb210\" data-id=\"759eb210\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26bd7a67 elementor-widget elementor-widget-heading\" data-id=\"26bd7a67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ange\u00adli\u00adka F\u00fcrst\u00adler<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-286b5d0 elementor-widget elementor-widget-heading\" data-id=\"286b5d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Spros\u00adsen &amp; Mikro\u00adgr\u00fcn ein\u00adfach &amp; leicht gemacht mit Top Pra\u00adxis Tipps<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-530e7c5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"530e7c5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-33c9e4da\" data-id=\"33c9e4da\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-60012813 elementor-widget elementor-widget-text-editor\" data-id=\"60012813\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ange\u00adli\u00adka F\u00fcrst\u00adler lebt f\u00fcr <strong>Ganz\u00adheit\u00adli\u00adche Gesund\u00adheit &amp; Life\u00adstyle, Spros\u00adsen, Mikro\u00adgr\u00fcn, High\u00adVi\u00adbe\u00ae Food<\/strong> (hoch\u00adschwin\u00adgen\u00adde Lebens\u00admit\u00adtel). Ange\u00adli\u00adka ist krea\u00adtiv-vega\u00adne K\u00f6chin, Autorin, Fit\u00adness &amp; Lie\u00adfe\u00adstyle-Coach. Sie ist Mit\u00adbe\u00adgr\u00fcn\u00adde\u00adrin und <strong>Aus\u00adbil\u00adde\u00adrin f\u00fcr die GET-Aus\u00adbil\u00addung zum\/r Diplo\u00admier\u00adten Ganz\u00adheit\u00adli\u00adchen Ern\u00e4h\u00adrungs\u00adtrai\u00adne\u00adrIn<\/strong>. Ange\u00adli\u00adka ist unse\u00adre Exper\u00adtin f\u00fcr <strong>Spros\u00adsen und Keim\u00adlin\u00adge<\/strong>, die wir auf der <strong>Fens\u00adter\u00adbank<\/strong> and <strong>K\u00fcchen\u00adtisch<\/strong> zie\u00adhen k\u00f6n\u00adnen. Sie hat zwei B\u00fccher ver\u00ad\u00f6f\u00adfent\u00adlicht: \u201eSpros\u00adsen und Mikro\u00adgr\u00fcn\u201c. Danach \u201eSpros\u00adsen &amp; Keim\u00adlin\u00adge. 15-Minu\u00adten-Rezep\u00adte mit Vital\u00adstoff-Food\u201c. Im Sep\u00adtem\u00adber wird \u201eHigh Vibe Food: Beschwingt &amp; gl\u00fcck\u00adlich mit Rezep\u00adten vol\u00adler Lebens\u00aden\u00ader\u00adgie und Genuss\u201c erschei\u00adnen.<\/p><p><strong>Con\u00adtents:<\/strong><\/p><p>Die Spros\u00adsen\u00adqueen Ange\u00adli\u00adka F\u00fcrst\u00adler bringt uns auf ihre bezau\u00adbern\u00adde leben\u00addi\u00adge Art die <strong>gesund\u00adheit\u00adli\u00adchen Vor\u00adtei\u00adle<\/strong> from <strong>Spros\u00adsen und Micro\u00adgreens<\/strong> n\u00e4her. Sie erkl\u00e4rt, war\u00adum das <strong>Pflan\u00adzen\u00adgr\u00fcn<\/strong>that <strong>Chlo\u00adro\u00adphyll<\/strong>, so wich\u00adtig ist. Sie spricht zu den M\u00f6g\u00adlich\u00adkei\u00adten, Spros\u00adsen, Micro\u00adgreens und Gr\u00e4\u00adser zu Hau\u00adse anzu\u00adbau\u00aden, die\u00adse in die Ern\u00e4h\u00adrung ein\u00adzu\u00adbau\u00aden und wor\u00adauf zu ach\u00adten ist. Mit \u201cSpros\u00adsen &amp; Mikro\u00adgr\u00fcn ein\u00adfach &amp; leicht gemacht\u201d&nbsp; gibt Ange\u00adli\u00adka Top-Pra\u00adxis Tipps, nennt die h\u00e4u\u00adfigs\u00adten Feh\u00adler und wie Du sie ver\u00admei\u00addest. Ange\u00adli\u00adka gibt uns lecke\u00adre Rezept\u00adideen mit allem, was Du brauchst, um die ulti\u00adma\u00adti\u00adven Super\u00adfoods das gan\u00adze Jahr \u00fcber mit Leich\u00adtig\u00adkeit in Dein Leben zu inte\u00adgrie\u00adren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a85dfab elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"a85dfab\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc10acd elementor-widget elementor-widget-heading\" data-id=\"cc10acd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Noch mehr Infos: KOSTENFREIE MASTERCLASS mit Ange\u00adli\u00adkA F\u00fcrst\u00adler: Zeit f\u00fcr Spros\u00adsen<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7ec4442f elementor-widget elementor-widget-text-editor\" data-id=\"7ec4442f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><a href=\"https:\/\/www.angelikafurstler.de\/a\/23901\/DXnX27AF\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #cc3b36;\">Die\u00adsen und kom\u00admen\u00adden Sonn\u00adtag 20 Uhr:<\/span><\/a><br>Spros\u00adse dir n\u00e4hr\u00adstoff\u00adrei\u00adche Super\u00adfoods ein\u00adfach zuhau\u00adse. Unab\u00adh\u00e4n\u00adgig &amp; kos\u00adten\u00adg\u00fcns\u00adtig. Spros\u00adsen, Mikro\u00adgr\u00fcn, Keim\u00adlin\u00adge &amp; Co sind gefrag\u00adter als je zuvor. Sie sind nicht nur abso\u00adlu\u00adte Vital\u00adstoff\u00adwun\u00adder und \u201eHigh\u00adVi\u00adbe\u00ae Foods\u201c, son\u00addern auch klas\u00adsi\u00adsche \u201eSur\u00advi\u00adval\u00adfoods\u201c \u2013 beson\u00adders jetzt sehr prak\u00adtisch, da Du Dich immer mit fri\u00adschen LEBENs\u00admit\u00adteln ver\u00adsor\u00adgen kannst, sogar ohne Dein Haus zu ver\u00adlas\u00adsen und damit mega lecke\u00adres, n\u00e4hr\u00adstoff\u00adrei\u00adches und ener\u00adgie\u00adge\u00adla\u00adde\u00adnes Essen f\u00fcr die gan\u00adze Fami\u00adly zube\u00adrei\u00adten kannst. Wie\u00adso es cle\u00adver ist, genau jetzt Spros\u00adsen in Dein Leben zu inte\u00adgrie\u00adren + wie Du das ganz leicht machst, erf\u00e4hrst Du in die\u00adsem kos\u00adten\u00adfrei\u00aden Web\u00adi\u00adnar mit Autorin, Spros\u00adsen- und High\u00adVi\u00adbe\u00ae Food &amp; Life\u00adstyle-Exper\u00adtin Ange\u00adli\u00adkA F\u00fcrst\u00adler. \ud83c\udf31<\/p><p><span style=\"color: #cc3b36;\"><a style=\"color: #cc3b36;\" href=\"https:\/\/www.angelikafurstler.de\/a\/23901\/DXnX27AF\" target=\"_blank\" rel=\"noopener\">Hier geht es zur Anmel\u00addung.<\/a><\/span><\/p><p><a href=\"https:\/\/www.angelikafurstler.de\/a\/23901\/DXnX27AF\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-26580 size-full\" src=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/04\/zeit-fuer-sprossen-angelika-fuerstler.avif\" alt width=\"178\" height=\"178\" srcset=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/04\/zeit-fuer-sprossen-angelika-fuerstler.avif 178w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/04\/zeit-fuer-sprossen-angelika-fuerstler-150x150.avif 150w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/04\/zeit-fuer-sprossen-angelika-fuerstler-12x12.avif 12w\" sizes=\"auto, (max-width: 178px) 100vw, 178px\"><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9321faa elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"9321faa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-30eaca14 elementor-widget elementor-widget-heading\" data-id=\"30eaca14\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">GET-Aus\u00adbil\u00addung zum\/r Diplo\u00admier\u00adten Ganz\u00adheit\u00adli\u00adchen Ern\u00e4h\u00adrungs\u00adtrai\u00adne\u00adrin<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7012e86e elementor-widget elementor-widget-text-editor\" data-id=\"7012e86e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Ange\u00adli\u00adka F\u00fcrst\u00adler ist Mit\u00adbe\u00adgr\u00fcn\u00adde\u00adrin und Tuto\u00adrin der zer\u00adti\u00adfi\u00adzier\u00adten <a href=\"https:\/\/www.ernaehrungstrainerin.proges.at\/a\/20749\/D25RwJDo\" target=\"_blank\" rel=\"noopener\">GET-Aus\u00adbil\u00addung zum\/r Diplo\u00admier\u00adten Ganz\u00adheit\u00adli\u00adchen Ern\u00e4h\u00adrungs\u00adtrai\u00adne\u00adrin<\/a>. Am <strong>1. Okto\u00adber<\/strong> star\u00adtet wie\u00adder die n\u00e4chs\u00adte Run\u00adde der <em>GET-Aus\u00adbil\u00addung zum\/r Ganz\u00adheit\u00adli\u00adchen Ern\u00e4h\u00adrungs\u00adtrai\u00adne\u00adrIn. <\/em>Hier sind wei\u00adte\u00adre <a href=\"https:\/\/www.ernaehrungstrainerin.proges.at\/a\/17633\/D25RwJDo\" target=\"_blank\" rel=\"noopener\">Infor\u00adma\u00adtio\u00adnen<\/a>.<\/p>\n<p><a href=\"https:\/\/www.ernaehrungstrainerin.proges.at\/a\/30018\/D25RwJDo\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-33072 size-large\" src=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein-1024x559.avif\" alt width=\"800\" height=\"437\" srcset=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein-1024x559.avif 1024w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein-300x164.avif 300w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein-768x419.avif 768w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein-1536x838.avif 1536w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein-18x10.avif 18w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein-1320x720.avif 1320w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/GET_Ausbildung_Ganzheitlicher_ErnaehrungstrainerIn_klein.avif 1980w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\"><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1282766 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"1282766\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4fb856f1 elementor-widget elementor-widget-heading\" data-id=\"4fb856f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Bonus: E\u2011Book \u201eMikro\u00adgr\u00fcn f\u00fcr den Bal\u00adkon\u201c<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4815a787 elementor-widget elementor-widget-button\" data-id=\"4815a787\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/04\/AngelikA_Furstler_Mikrogru\u0308n-fu\u0308r-den-Balkon_2021_Print-final.pdf\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Zum Down\u00adload<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71f850a0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"71f850a0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bb28e2f elementor-widget elementor-widget-heading\" data-id=\"5bb28e2f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Books<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4cbc54ca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4cbc54ca\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-59a19da2\" data-id=\"59a19da2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55ae8617 elementor-widget elementor-widget-image\" data-id=\"55ae8617\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amzn.to\/2OpHioU\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"213\" height=\"300\" src=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/angelika-fu\u0308rstler-213x300.avif\" class=\"attachment-medium size-medium wp-image-32286\" alt srcset=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/angelika-fu\u0308rstler-213x300.avif 213w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/angelika-fu\u0308rstler.avif 354w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-754e78c2\" data-id=\"754e78c2\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d1180fc elementor-widget elementor-widget-image\" data-id=\"6d1180fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amzn.to\/31LA9SI\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"251\" height=\"300\" src=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/angelika_fuerstler-251x300.avif\" class=\"attachment-medium size-medium wp-image-32287\" alt srcset=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/angelika_fuerstler-251x300.avif 251w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/angelika_fuerstler.avif 419w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-2271fc9e\" data-id=\"2271fc9e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d8bb149 elementor-widget elementor-widget-image\" data-id=\"d8bb149\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/amzn.to\/3fzNA0i\" target=\"_blank\" rel=\"nofollow\">\n\t\t\t\t\t\t\t<img decoding=\"async\" width=\"251\" height=\"300\" src=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/High-Vibe-Food-angelika-fu\u0308rstler-251x300.avif\" class=\"attachment-medium size-medium wp-image-32288\" alt loading=\"lazy\" srcset=\"https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/High-Vibe-Food-angelika-fu\u0308rstler-251x300.avif 251w, https:\/\/bio-balkon.de\/wp-content\/uploads\/2021\/08\/High-Vibe-Food-angelika-fu\u0308rstler.avif 419w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\">\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-inner-column elementor-element elementor-element-40234cf6\" data-id=\"40234cf6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-89b1c29 elementor-widget elementor-widget-text-editor\" data-id=\"89b1c29\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>Das Buch \u201eSpros\u00adsen &amp; Mikro\u00adgr\u00fcn\u201c ist Bestand\u00adteil vom Gewinn\u00adspiel. Infor\u00adma\u00adtio\u00adnen zum Gewinn\u00adspiel fin\u00addest Du <a href=\"https:\/\/bio-balkon.de\/en\/keimling-naturkost\/\" target=\"_blank\" rel=\"noopener\">here<\/a>.<\/p><p>The book\u00ads\u00adto\u00adre around the cor\u00adner should always be your first choice.&nbsp;<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68fcdd2d elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"68fcdd2d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2fe85c40 elementor-widget elementor-widget-heading\" data-id=\"2fe85c40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Social Media<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-491ca82d elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"491ca82d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/angelikaalmiralltorrelfurstler\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ange\u00adli\u00adka Maria Almi\u00adrall-Tor\u00adrel F\u00fcrst\u00adler<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/angelikafurstleroffiziell\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ange\u00adli\u00adkA F\u00fcrst\u00adler Offi\u00adzi\u00adell<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.facebook.com\/angelikafurstler\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-facebook\" viewBox=\"0 0 512 512\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ange\u00adli\u00adka F\u00fcrst\u00adler<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-813438 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"813438\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/angelikafurstler_offiziell\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">angelikafurstler_offiziell<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-63ab9ed5 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"63ab9ed5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.instagram.com\/angelikafurstler\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-instagram\" viewBox=\"0 0 448 512\"><path d=\"M224.1 141c-63.6 0-114.9 51.3-114.9 114.9s51.3 114.9 114.9 114.9S339 319.5 339 255.9 287.7 141 224.1 141zm0 189.6c-41.1 0-74.7-33.5-74.7-74.7s33.5-74.7 74.7-74.7 74.7 33.5 74.7 74.7-33.6 74.7-74.7 74.7zm146.4-194.3c0 14.9-12 26.8-26.8 26.8-14.9 0-26.8-12-26.8-26.8s12-26.8 26.8-26.8 26.8 12 26.8 26.8zm76.1 27.2c-1.7-35.9-9.9-67.7-36.2-93.9-26.2-26.2-58-34.4-93.9-36.2-37-2.1-147.9-2.1-184.9 0-35.8 1.7-67.6 9.9-93.9 36.1s-34.4 58-36.2 93.9c-2.1 37-2.1 147.9 0 184.9 1.7 35.9 9.9 67.7 36.2 93.9s58 34.4 93.9 36.2c37 2.1 147.9 2.1 184.9 0 35.9-1.7 67.7-9.9 93.9-36.2 26.2-26.2 34.4-58 36.2-93.9 2.1-37 2.1-147.8 0-184.8zM398.8 388c-7.8 19.6-22.9 34.7-42.6 42.6-29.5 11.7-99.5 9-132.1 9s-102.7 2.6-132.1-9c-19.6-7.8-34.7-22.9-42.6-42.6-11.7-29.5-9-99.5-9-132.1s-2.6-102.7 9-132.1c7.8-19.6 22.9-34.7 42.6-42.6 29.5-11.7 99.5-9 132.1-9s102.7-2.6 132.1 9c19.6 7.8 34.7 22.9 42.6 42.6 11.7 29.5 9 99.5 9 132.1s2.7 102.7-9 132.1z\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ange\u00adli\u00adkaf\u00adurst\u00adler<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f1f8e4e elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"2f1f8e4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.youtube.com\/channel\/UCLWhLI78DqeMthsh9HII7Eg\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fab-youtube\" viewBox=\"0 0 576 512\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">ange\u00adli\u00adka f\u00fcrst\u00adler<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-632934e8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"632934e8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4e767cf8 elementor-widget elementor-widget-heading\" data-id=\"4e767cf8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Web\u00adsite<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6532ff20 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"6532ff20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.angelikafurstler.de\/\" target=\"_blank\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-external-link-alt\" viewBox=\"0 0 512 512\"><path d=\"M432,320H400a16,16,0,0,0-16,16V448H64V128H208a16,16,0,0,0,16-16V80a16,16,0,0,0-16-16H48A48,48,0,0,0,0,112V464a48,48,0,0,0,48,48H400a48,48,0,0,0,48-48V336A16,16,0,0,0,432,320ZM488,0h-128c-21.37,0-32.05,25.91-17,41l35.73,35.73L135,320.37a24,24,0,0,0,0,34L157.67,377a24,24,0,0,0,34,0L435.28,133.32,471,169c15,15,41,4.5,41-17V24A24,24,0,0,0,488,0Z\" \/><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Ange\u00adli\u00adka F\u00fcrst\u00adler<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":15269,"template":"","meta":{"_acf_changed":false,"wp_typography_post_enhancements_disabled":false},"class_list":["post-32293","experten","type-experten","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bio-balkon.de\/en\/wp-json\/wp\/v2\/experten\/32293","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bio-balkon.de\/en\/wp-json\/wp\/v2\/experten"}],"about":[{"href":"https:\/\/bio-balkon.de\/en\/wp-json\/wp\/v2\/types\/experten"}],"version-history":[{"count":0,"href":"https:\/\/bio-balkon.de\/en\/wp-json\/wp\/v2\/experten\/32293\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bio-balkon.de\/en\/wp-json\/wp\/v2\/media\/15269"}],"wp:attachment":[{"href":"https:\/\/bio-balkon.de\/en\/wp-json\/wp\/v2\/media?parent=32293"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}